{"id":5209,"date":"2018-12-27T19:11:38","date_gmt":"2018-12-27T19:11:38","guid":{"rendered":"http:\/\/www.galloportugal.com\/produto\/vinagre-premium-balsamico-de-modena\/"},"modified":"2023-09-11T11:58:28","modified_gmt":"2023-09-11T11:58:28","slug":"balsamico-de-modena","status":"publish","type":"produto","link":"https:\/\/victorguedes.com\/es\/vinagres-es\/balsamico-de-modena\/","title":{"rendered":"Bals\u00e1mico de M\u00f3dena"},"content":{"rendered":"<p>Mezcla de vinagre bals\u00e1mico tradicional de M\u00f3dena y mosto de uva dulce tard\u00eda. Producido en Italia y envejecido en barricas de roble, sabor y aroma agridulce, equilibrado con notas de madera.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se hace en Italia, se deshace en su paladar<\/p>\n","protected":false},"featured_media":21932,"template":"","meta":{"iawp_total_views":35},"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/victorguedes.com\/es\/wp-json\/wp\/v2\/produto\/5209"}],"collection":[{"href":"https:\/\/victorguedes.com\/es\/wp-json\/wp\/v2\/produto"}],"about":[{"href":"https:\/\/victorguedes.com\/es\/wp-json\/wp\/v2\/types\/produto"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/victorguedes.com\/es\/wp-json\/wp\/v2\/media\/21932"}],"wp:attachment":[{"href":"https:\/\/victorguedes.com\/es\/wp-json\/wp\/v2\/media?parent=5209"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}